{"id":15359,"date":"2026-03-27T09:29:40","date_gmt":"2026-03-27T08:29:40","guid":{"rendered":"https:\/\/grill-master.shop\/gree\/produkt\/grill-gazowy-yao-51-19kw-zeliwny-ruszt-palnik-na-podczerwien-yato-yg-20031\/"},"modified":"2026-03-27T09:29:40","modified_gmt":"2026-03-27T08:29:40","slug":"grill-gazowy-yao-51-19kw-zeliwny-ruszt-palnik-na-podczerwien-yato-yg-20031","status":"publish","type":"product","link":"https:\/\/torxino.shop\/grill\/produkt\/grill-gazowy-yao-51-19kw-zeliwny-ruszt-palnik-na-podczerwien-yato-yg-20031\/","title":{"rendered":"GRILL GAZOWY Yao 5+1 19KW \u017celiwny ruszt palnik na podczerwie\u0144 YATO YG-20031"},"content":{"rendered":"<div style=\"font-family: Arial, sans-serif; line-height: 1.6; color: #333; padding: 20px; clear: both; display: block; width: 100%; float: none; position: static; overflow: hidden;\">\n<div style=\"clear: both; display: block; margin: 10px 0;\">\n<div style=\"clear: both; display: block; margin: 10px 0;\">\n<div style=\"clear: both; display: block; margin: 10px 0;\">\n<div  style=\"max-width:1200px;max-height:421px\">\n<div style=\"clear: both; display: block; margin: 10px 0;\">\n<div style=\"clear: both; width: 100%; display: block; margin: 20px 0; padding: 0; float: none; position: static; text-align: center;\"><img decoding=\"async\"  src=\"https:\/\/a.allegroimg.com\/original\/113a91\/6ff038e84de89117ba6b34ef4741\/GRILL-GAZOWY-Yao-5-1-19KW-zeliwny-ruszt-palnik-na-podczerwien-YATO-YG-20031-Liczba-palnikow-5\" srcset=\"https:\/\/a.allegroimg.com\/original\/113a91\/6ff038e84de89117ba6b34ef4741\/GRILL-GAZOWY-Yao-5-1-19KW-zeliwny-ruszt-palnik-na-podczerwien-YATO-YG-20031-Liczba-palnikow-5 360w,https:\/\/a.allegroimg.com\/original\/113a91\/6ff038e84de89117ba6b34ef4741\/GRILL-GAZOWY-Yao-5-1-19KW-zeliwny-ruszt-palnik-na-podczerwien-YATO-YG-20031-Liczba-palnikow-5 720w,https:\/\/a.allegroimg.com\/original\/113a91\/6ff038e84de89117ba6b34ef4741\/GRILL-GAZOWY-Yao-5-1-19KW-zeliwny-ruszt-palnik-na-podczerwien-YATO-YG-20031-Liczba-palnikow-5 1024w,https:\/\/a.allegroimg.com\/original\/113a91\/6ff038e84de89117ba6b34ef4741\/GRILL-GAZOWY-Yao-5-1-19KW-zeliwny-ruszt-palnik-na-podczerwien-YATO-YG-20031-Liczba-palnikow-5 1200w,https:\/\/a.allegroimg.com\/original\/113a91\/6ff038e84de89117ba6b34ef4741\/GRILL-GAZOWY-Yao-5-1-19KW-zeliwny-ruszt-palnik-na-podczerwien-YATO-YG-20031-Liczba-palnikow-5 1200w\" sizes=\"100vw\" width=\"1200px\" alt=\"GRILL GAZOWY Yao 5+1 19KW \u017celiwny ruszt palnik na podczerwie\u0144 YATO YG-20031 Liczba palnik\u00f3w 5\" style=\"max-width: 100%; height: auto; display: block; margin: 0 auto;\"><\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div style=\"clear: both; display: block; margin: 10px 0;\">\n<div style=\"clear: both; display: block; margin: 10px 0;\">\n<div style=\"clear: both; display: block; margin: 10px 0;\">\n<h1>YATO GRILL GAZOWY YAO 5+1 19KW CZARNY YG-20031<\/h1>\n<\/div>\n<\/div>\n<\/div>\n<div style=\"clear: both; display: block; margin: 10px 0;\">\n<div style=\"clear: both; display: block; margin: 10px 0;\">\n<div style=\"clear: both; display: block; margin: 10px 0;\">\n<h3 style=\"color: #2c5aa0; font-size: 18px; margin: 30px 0 15px 0; font-weight: bold; clear: both; display: block; width: 100%; float: none; position: static;\">Grill gazowy yao 5+1 19kw czarny<\/h3>\n<\/div>\n<\/div>\n<\/div>\n<div style=\"clear: both; display: block; margin: 10px 0;\">\n<div style=\"clear: both; display: block; margin: 10px 0;\">\n<div style=\"clear: both; display: block; margin: 10px 0;\">\n<p style=\"margin: 15px 0; line-height: 1.8; clear: both; display: block; width: 100%; float: none; position: static;\">Wolnostoj\u0105cy grill gazowy serii Yao&nbsp;z 6 palnikami&nbsp;o \u0142\u0105cznej mocy 19,5&nbsp;kW i praktycznymi dodatkami u\u0142atwiaj\u0105cymi przygotowywanie potraw na \u015bwie\u017cym powietrzu. Wyposa\u017cony w 3&nbsp;\u017celiwne&nbsp;ruszty o du\u017cej powierzchni roboczej i&nbsp;kratk\u0119 podgrzewaj\u0105c\u0105 z wysokiej jako\u015bci&nbsp;stali nierdzewnej, trwa\u0142e i odporne na korozj\u0119 oraz uszkodzenia.&nbsp; &nbsp;<\/p>\n<h3 style=\"color: #2c5aa0; font-size: 18px; margin: 30px 0 15px 0; font-weight: bold; clear: both; display: block; width: 100%; float: none; position: static;\">Parametry:<\/h3>\n<ul style=\"margin: 15px 0; padding-left: 20px; clear: both; display: block; width: 100%; float: none; position: static;\">\n<li style=\"margin: 5px 0; padding: 2px 0; clear: both; display: list-item; float: none; position: static;\">wymiary grilla:&nbsp;1330 x 570 x 1120 mm<\/li>\n<li style=\"margin: 5px 0; padding: 2px 0; clear: both; display: list-item; float: none; position: static;\">materia\u0142: stal malowana proszkowo na kolor czarny<\/li>\n<li style=\"margin: 5px 0; padding: 2px 0; clear: both; display: list-item; float: none; position: static;\">materia\u0142 ruszt\u00f3w: \u017celiwo<\/li>\n<li style=\"margin: 5px 0; padding: 2px 0; clear: both; display: list-item; float: none; position: static;\">zasilany gazem&nbsp;butan G30, propan G31<\/li>\n<li style=\"margin: 5px 0; padding: 2px 0; clear: both; display: list-item; float: none; position: static;\">rodzaj pojemnika z gazem:&nbsp;typ EN 498: I3B\/P(37)<\/li>\n<li style=\"margin: 5px 0; padding: 2px 0; clear: both; display: list-item; float: none; position: static;\">ci\u015bnienie gazu:&nbsp;37 mbar<\/li>\n<li style=\"margin: 5px 0; padding: 2px 0; clear: both; display: list-item; float: none; position: static;\">zu\u017cycie gazu:&nbsp;1419 g\/h<\/li>\n<li style=\"margin: 5px 0; padding: 2px 0; clear: both; display: list-item; float: none; position: static;\">waga: 48,5 kg<\/li>\n<\/ul>\n<\/div>\n<\/div>\n<\/div>\n<div style=\"clear: both; display: block; margin: 10px 0;\">\n<div style=\"clear: both; display: block; margin: 10px 0;\">\n<div style=\"clear: both; display: block; margin: 10px 0;\">\n<h3 style=\"color: #2c5aa0; font-size: 18px; margin: 30px 0 15px 0; font-weight: bold; clear: both; display: block; width: 100%; float: none; position: static;\">Cechy:<\/h3>\n<ul style=\"margin: 15px 0; padding-left: 20px; clear: both; display: block; width: 100%; float: none; position: static;\">\n<li style=\"margin: 5px 0; padding: 2px 0; clear: both; display: list-item; float: none; position: static;\">5 palnik\u00f3w&nbsp;g\u0142\u00f3wnych&nbsp;o mocy 3 kW ka\u017cdy, w tym palnik o du\u017cej mocy 4 kW (4 x 3 kW, 1 x 4 kW)<\/li>\n<li style=\"margin: 5px 0; padding: 2px 0; clear: both; display: list-item; float: none; position: static;\">palnik boczny na podczerwie\u0144 o mocy 3,5 kW osi\u0105ga ekstremalnie wysok\u0105 temperatur\u0119 800 stopni, umo\u017cliwiaj\u0105c szybkie obsma\u017cenie (tzw. sear) i&nbsp;przyrz\u0105dzanie stek\u00f3w (nie zaleca si\u0119 u\u017cywania jako palnika podgrzewaj\u0105cego garnki, patelnie itd.)<\/li>\n<li style=\"margin: 5px 0; padding: 2px 0; clear: both; display: list-item; float: none; position: static;\">automatyczny zapalnik w pokr\u0119tle pozwala \u0142atwo i szybko&nbsp;odpala\u0107&nbsp;grilla<\/li>\n<li style=\"margin: 5px 0; padding: 2px 0; clear: both; display: list-item; float: none; position: static;\">sterowanie&nbsp;grillem za pomoc\u0105 pokr\u0119te\u0142 u\u0142atwia obs\u0142ug\u0119<\/li>\n<li style=\"margin: 5px 0; padding: 2px 0; clear: both; display: list-item; float: none; position: static;\">4 profilowane, emaliowane os\u0142ony palnika (aromatyzery) z wyci\u0119ciami<\/li>\n<li style=\"margin: 5px 0; padding: 2px 0; clear: both; display: list-item; float: none; position: static;\">1 profilowany, wykonany ze stali nierdzewnej, aromatyzer z wyci\u0119ciami do palnika 4 kW<\/li>\n<li style=\"margin: 5px 0; padding: 2px 0; clear: both; display: list-item; float: none; position: static;\">\u017celiwny ruszt o powierzchni 700 x 420 mm szybko si\u0119 nagrzewa,&nbsp;d\u0142ugo utrzymuje ciep\u0142o i zapewnia bardzo du\u017co miejsca&nbsp;na przygotowanie wielu r\u00f3\u017cnych potraw<\/li>\n<li style=\"margin: 5px 0; padding: 2px 0; clear: both; display: list-item; float: none; position: static;\">ruszt ze stali nierdzewnej nad palnikiem infrared (podczerwie\u0144)<\/li>\n<li style=\"margin: 5px 0; padding: 2px 0; clear: both; display: list-item; float: none; position: static;\">kratka do pogrzewania nad rusztem o wymiarach&nbsp;677 x 120 mm&nbsp;wykonana ze stali nierdzewnej<\/li>\n<li style=\"margin: 5px 0; padding: 2px 0; clear: both; display: list-item; float: none; position: static;\">dwuwarstwowa pokrywa z wbudowanym termometrem ze stali nierdzewnej zapewnia optymaln\u0105 cyrkulacj\u0119 powietrza i sta\u0142\u0105 kontrol\u0119 temperatury, nadaj\u0105c potrawom idealny smak i aromat<\/li>\n<li style=\"margin: 5px 0; padding: 2px 0; clear: both; display: list-item; float: none; position: static;\">pojemna szafka 700 x 455 x 555 mm zamykana na dwuwarstwowe drzwi&nbsp;umo\u017cliwia przechowywanie&nbsp;niezb\u0119dnych akcesori\u00f3w i&nbsp;przypraw<\/li>\n<li style=\"margin: 5px 0; padding: 2px 0; clear: both; display: list-item; float: none; position: static;\">4 obrotowe k\u00f3\u0142ka z hamulcami u\u0142atwiaj\u0105 swobodne manewrowanie grillem i zapewniaj\u0105 stabilno\u015b\u0107 na ka\u017cdym rodzaju pod\u0142o\u017ca<\/li>\n<li style=\"margin: 5px 0; padding: 2px 0; clear: both; display: list-item; float: none; position: static;\">du\u017ce uchwyty w pokrywie i drzwiach szafki<\/li>\n<li style=\"margin: 5px 0; padding: 2px 0; clear: both; display: list-item; float: none; position: static;\">wyodr\u0119bniona&nbsp;kiesze\u0144 na butl\u0119 gazow\u0105 stabilizuje j\u0105 w trakcie operowania grillem<\/li>\n<li style=\"margin: 5px 0; padding: 2px 0; clear: both; display: list-item; float: none; position: static;\">wysuwana tacka ociekowa na t\u0142uszcz u\u0142atwia utrzymanie czysto\u015bci w trakcie grillowania i ko\u0144cowe sprz\u0105tanie<\/li>\n<li style=\"margin: 5px 0; padding: 2px 0; clear: both; display: list-item; float: none; position: static;\">boczne p\u00f3\u0142ki wyposa\u017cone w wyci\u0105gan\u0105 drewnian\u0105 desk\u0119 do krojenia i&nbsp;stalowy pojemnik nadaj\u0105cy si\u0119 do przechowywania sk\u0142adnik\u00f3w lub gotowych da\u0144<\/li>\n<li style=\"margin: 5px 0; padding: 2px 0; clear: both; display: list-item; float: none; position: static;\">boczne uchwyty i koszyki na perforacji tworz\u0105 dodatkowe miejsce do&nbsp;odk\u0142adania akcesori\u00f3w do grilla, produkt\u00f3w spo\u017cywczych, r\u0119cznik\u00f3w<\/li>\n<li style=\"margin: 5px 0; padding: 2px 0; clear: both; display: list-item; float: none; position: static;\">p\u00f3\u0142ka po wewn\u0119trznej stronie drzwi&nbsp;idealnie sprawdza si\u0119 do przechowywania w\u0119\u017cszych pojemnik\u00f3w, np. sos\u00f3w, butelek, przypraw<\/li>\n<\/ul>\n<\/div>\n<\/div>\n<div style=\"clear: both; display: block; margin: 10px 0;\">\n<div style=\"clear: both; display: block; margin: 10px 0;\">\n<div  style=\"max-width:2560px;max-height:2278px\">\n<div style=\"clear: both; display: block; margin: 10px 0;\">\n<div style=\"clear: both; width: 100%; display: block; margin: 20px 0; padding: 0; float: none; position: static; text-align: center;\"><img decoding=\"async\"  src=\"https:\/\/a.allegroimg.com\/original\/11673d\/9c77220c4d97b831f6878fe7afa7\/GRILL-GAZOWY-Yao-5-1-19KW-zeliwny-ruszt-palnik-na-podczerwien-YATO-YG-20031\" srcset=\"https:\/\/a.allegroimg.com\/original\/11673d\/9c77220c4d97b831f6878fe7afa7\/GRILL-GAZOWY-Yao-5-1-19KW-zeliwny-ruszt-palnik-na-podczerwien-YATO-YG-20031 360w,https:\/\/a.allegroimg.com\/original\/11673d\/9c77220c4d97b831f6878fe7afa7\/GRILL-GAZOWY-Yao-5-1-19KW-zeliwny-ruszt-palnik-na-podczerwien-YATO-YG-20031 720w,https:\/\/a.allegroimg.com\/original\/11673d\/9c77220c4d97b831f6878fe7afa7\/GRILL-GAZOWY-Yao-5-1-19KW-zeliwny-ruszt-palnik-na-podczerwien-YATO-YG-20031 1024w,https:\/\/a.allegroimg.com\/original\/11673d\/9c77220c4d97b831f6878fe7afa7\/GRILL-GAZOWY-Yao-5-1-19KW-zeliwny-ruszt-palnik-na-podczerwien-YATO-YG-20031 1440w,https:\/\/a.allegroimg.com\/original\/11673d\/9c77220c4d97b831f6878fe7afa7\/GRILL-GAZOWY-Yao-5-1-19KW-zeliwny-ruszt-palnik-na-podczerwien-YATO-YG-20031 2560w\" sizes=\"(min-width: 1200px) 560px, (min-width: 992px) 50vw, 100vw\" width=\"2560px\" alt=\"GRILL GAZOWY Yao 5+1 19KW \u017celiwny ruszt palnik na podczerwie\u0144 YATO YG-20031\" style=\"max-width: 100%; height: auto; display: block; margin: 0 auto;\"><\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div style=\"clear: both; display: block; margin: 10px 0;\">\n<div style=\"clear: both; display: block; margin: 10px 0;\">\n<div style=\"clear: both; display: block; margin: 10px 0;\">\n<div  style=\"max-width:2560px;max-height:1781px\">\n<div style=\"clear: both; display: block; margin: 10px 0;\">\n<div style=\"clear: both; width: 100%; display: block; margin: 20px 0; padding: 0; float: none; position: static; text-align: center;\"><img decoding=\"async\"  src=\"https:\/\/a.allegroimg.com\/original\/114ae7\/268f6ae743f795da931739cbffbb\/GRILL-GAZOWY-Yao-5-1-19KW-zeliwny-ruszt-palnik-na-podczerwien-YATO-YG-20031-Moc-19-kW\" srcset=\"https:\/\/a.allegroimg.com\/original\/114ae7\/268f6ae743f795da931739cbffbb\/GRILL-GAZOWY-Yao-5-1-19KW-zeliwny-ruszt-palnik-na-podczerwien-YATO-YG-20031-Moc-19-kW 360w,https:\/\/a.allegroimg.com\/original\/114ae7\/268f6ae743f795da931739cbffbb\/GRILL-GAZOWY-Yao-5-1-19KW-zeliwny-ruszt-palnik-na-podczerwien-YATO-YG-20031-Moc-19-kW 720w,https:\/\/a.allegroimg.com\/original\/114ae7\/268f6ae743f795da931739cbffbb\/GRILL-GAZOWY-Yao-5-1-19KW-zeliwny-ruszt-palnik-na-podczerwien-YATO-YG-20031-Moc-19-kW 1024w,https:\/\/a.allegroimg.com\/original\/114ae7\/268f6ae743f795da931739cbffbb\/GRILL-GAZOWY-Yao-5-1-19KW-zeliwny-ruszt-palnik-na-podczerwien-YATO-YG-20031-Moc-19-kW 1440w,https:\/\/a.allegroimg.com\/original\/114ae7\/268f6ae743f795da931739cbffbb\/GRILL-GAZOWY-Yao-5-1-19KW-zeliwny-ruszt-palnik-na-podczerwien-YATO-YG-20031-Moc-19-kW 2560w\" sizes=\"(min-width: 1200px) 560px, (min-width: 992px) 50vw, 100vw\" width=\"2560px\" alt=\"GRILL GAZOWY Yao 5+1 19KW \u017celiwny ruszt palnik na podczerwie\u0144 YATO YG-20031 Moc 19 kW\" style=\"max-width: 100%; height: auto; display: block; margin: 0 auto;\"><\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div style=\"clear: both; display: block; margin: 10px 0;\">\n<div style=\"clear: both; display: block; margin: 10px 0;\">\n<h3 style=\"color: #2c5aa0; font-size: 18px; margin: 30px 0 15px 0; font-weight: bold; clear: both; display: block; width: 100%; float: none; position: static;\">Mo\u017cliwo\u015b\u0107 dokupienia dodatkowych akcesori\u00f3w:<\/h3>\n<ul style=\"margin: 15px 0; padding-left: 20px; clear: both; display: block; width: 100%; float: none; position: static;\">\n<li style=\"margin: 5px 0; padding: 2px 0; clear: both; display: list-item; float: none; position: static;\">kamie\u0144 do pizzy YG-20024<\/li>\n<li style=\"margin: 5px 0; padding: 2px 0; clear: both; display: list-item; float: none; position: static;\">patelnia do grillowania YG-20141<\/li>\n<li style=\"margin: 5px 0; padding: 2px 0; clear: both; display: list-item; float: none; position: static;\">uchwyt na no\u017ce YG-20142<\/li>\n<li style=\"margin: 5px 0; padding: 2px 0; clear: both; display: list-item; float: none; position: static;\">uchwyt na r\u0119cznik YG-20144<\/li>\n<li style=\"margin: 5px 0; padding: 2px 0; clear: both; display: list-item; float: none; position: static;\">w\u0105\u017c z reduktorem VOREL 99670 lub 99671<\/li>\n<\/ul>\n<\/div>\n<\/div>\n<\/div>\n<div style=\"clear: both; display: block; margin: 10px 0;\">\n<div style=\"clear: both; display: block; margin: 10px 0;\">\n<div style=\"clear: both; display: block; margin: 10px 0;\">\n<h3 style=\"color: #2c5aa0; font-size: 18px; margin: 30px 0 15px 0; font-weight: bold; clear: both; display: block; width: 100%; float: none; position: static;\">SPECYFIKACJA:<\/h3>\n<ul style=\"margin: 15px 0; padding-left: 20px; clear: both; display: block; width: 100%; float: none; position: static;\">\n<li style=\"margin: 5px 0; padding: 2px 0; clear: both; display: list-item; float: none; position: static;\"><b>Seria:&nbsp;<\/b>Yao<\/li>\n<li style=\"margin: 5px 0; padding: 2px 0; clear: both; display: list-item; float: none; position: static;\"><b>Rozmiar rusztu: <\/b>700&#215;420 mm<\/li>\n<li style=\"margin: 5px 0; padding: 2px 0; clear: both; display: list-item; float: none; position: static;\"><b>Wysuwana taca na t\u0142uszcz: <\/b>tak<\/li>\n<li style=\"margin: 5px 0; padding: 2px 0; clear: both; display: list-item; float: none; position: static;\"><b>Ci\u015bnienie gazu: <\/b>37 mbar<\/li>\n<li style=\"margin: 5px 0; padding: 2px 0; clear: both; display: list-item; float: none; position: static;\"><b>Kszta\u0142t: <\/b>prostok\u0105tny<\/li>\n<li style=\"margin: 5px 0; padding: 2px 0; clear: both; display: list-item; float: none; position: static;\"><b>Liczba k\u00f3\u0142ek: <\/b>4<\/li>\n<li style=\"margin: 5px 0; padding: 2px 0; clear: both; display: list-item; float: none; position: static;\"><b>Liczba ruszt\u00f3w: <\/b>3<\/li>\n<li style=\"margin: 5px 0; padding: 2px 0; clear: both; display: list-item; float: none; position: static;\"><b>Kiesze\u0144 na butl\u0119 gazow\u0105: <\/b>tak<\/li>\n<li style=\"margin: 5px 0; padding: 2px 0; clear: both; display: list-item; float: none; position: static;\"><b>Zu\u017cycie gazu: <\/b>1419 g\/h<\/li>\n<li style=\"margin: 5px 0; padding: 2px 0; clear: both; display: list-item; float: none; position: static;\"><b>Wyko\u0144czenie powierzchni: <\/b>malowana proszkowo<\/li>\n<li style=\"margin: 5px 0; padding: 2px 0; clear: both; display: list-item; float: none; position: static;\"><b>Zapalnik w pokr\u0119tle: <\/b>tak<\/li>\n<li style=\"margin: 5px 0; padding: 2px 0; clear: both; display: list-item; float: none; position: static;\"><b>Masa: <\/b>48.5 kg<\/li>\n<li style=\"margin: 5px 0; padding: 2px 0; clear: both; display: list-item; float: none; position: static;\"><b>Materia\u0142 rusztu: <\/b>\u017celiwo<\/li>\n<li style=\"margin: 5px 0; padding: 2px 0; clear: both; display: list-item; float: none; position: static;\"><b>P\u00f3\u0142ka: <\/b>tak<\/li>\n<li style=\"margin: 5px 0; padding: 2px 0; clear: both; display: list-item; float: none; position: static;\"><b>Wymiary szafki: <\/b>700x455x555 mm<\/li>\n<li style=\"margin: 5px 0; padding: 2px 0; clear: both; display: list-item; float: none; position: static;\"><b>Rozmiar kratki podgrzewaj\u0105cej: <\/b>677&#215;120 mm<\/li>\n<li style=\"margin: 5px 0; padding: 2px 0; clear: both; display: list-item; float: none; position: static;\"><b>Typ: <\/b>przeno\u015bny<\/li>\n<li style=\"margin: 5px 0; padding: 2px 0; clear: both; display: list-item; float: none; position: static;\"><b>Uchwyt boczny: <\/b>nie<\/li>\n<li style=\"margin: 5px 0; padding: 2px 0; clear: both; display: list-item; float: none; position: static;\"><b>Moc: <\/b>19.5 (4&#215;3 + 4 + 3.5) kW<\/li>\n<li style=\"margin: 5px 0; padding: 2px 0; clear: both; display: list-item; float: none; position: static;\"><b>Wymiary: <\/b>1330x570x1120 mm<\/li>\n<li style=\"margin: 5px 0; padding: 2px 0; clear: both; display: list-item; float: none; position: static;\"><b>Regulacja wysoko\u015bci rusztu: <\/b>nie<\/li>\n<li style=\"margin: 5px 0; padding: 2px 0; clear: both; display: list-item; float: none; position: static;\"><b>K\u00f3\u0142ka: <\/b>tak<\/li>\n<li style=\"margin: 5px 0; padding: 2px 0; clear: both; display: list-item; float: none; position: static;\"><b>\u015arednica dyszy: <\/b>4&#215;0.82 + 1&#215;0.93 + 1&#215;0.86 mm<\/li>\n<li style=\"margin: 5px 0; padding: 2px 0; clear: both; display: list-item; float: none; position: static;\"><b>Popielnik: <\/b>nie<\/li>\n<li style=\"margin: 5px 0; padding: 2px 0; clear: both; display: list-item; float: none; position: static;\"><b>Kolor: <\/b>czarny<\/li>\n<li style=\"margin: 5px 0; padding: 2px 0; clear: both; display: list-item; float: none; position: static;\"><b>Liczba k\u00f3\u0142ek z hamulcem: <\/b>4<\/li>\n<li style=\"margin: 5px 0; padding: 2px 0; clear: both; display: list-item; float: none; position: static;\"><b>W\u0119dzarnia: <\/b>nie<\/li>\n<li style=\"margin: 5px 0; padding: 2px 0; clear: both; display: list-item; float: none; position: static;\"><b>Termometr: <\/b>tak<\/li>\n<li style=\"margin: 5px 0; padding: 2px 0; clear: both; display: list-item; float: none; position: static;\"><b>Rodzaj: <\/b>gazowy<\/li>\n<li style=\"margin: 5px 0; padding: 2px 0; clear: both; display: list-item; float: none; position: static;\"><b>Rodzaj pojemnika z gazem: <\/b>typ EN 498: I3B\/P(37)<\/li>\n<li style=\"margin: 5px 0; padding: 2px 0; clear: both; display: list-item; float: none; position: static;\"><b>Rodzaj gazu zasilaj\u0105cego: <\/b>butan G30|propan G31<\/li>\n<li style=\"margin: 5px 0; padding: 2px 0; clear: both; display: list-item; float: none; position: static;\"><b>Rozmiar p\u00f3\u0142ki: <\/b>310&#215;475 mm<\/li>\n<li style=\"margin: 5px 0; padding: 2px 0; clear: both; display: list-item; float: none; position: static;\"><b>Kratka do podgrzewania: <\/b>tak<\/li>\n<li style=\"margin: 5px 0; padding: 2px 0; clear: both; display: list-item; float: none; position: static;\"><b>Materia\u0142: <\/b>stal nierdzewna|stal<\/li>\n<li style=\"margin: 5px 0; padding: 2px 0; clear: both; display: list-item; float: none; position: static;\"><b>Przes\u0142ona do regulacji cyrkulacji powietrza: <\/b>nie<\/li>\n<li style=\"margin: 5px 0; padding: 2px 0; clear: both; display: list-item; float: none; position: static;\"><b>Pokrywa: <\/b>tak<\/li>\n<li style=\"margin: 5px 0; padding: 2px 0; clear: both; display: list-item; float: none; position: static;\"><b>Wielko\u015b\u0107: <\/b>grille du\u017ce<\/li>\n<li style=\"margin: 5px 0; padding: 2px 0; clear: both; display: list-item; float: none; position: static;\"><b>Liczba palnik\u00f3w:&nbsp;<\/b>6 (5 g\u0142\u00f3wnych i 1 dodatkowy)<\/li>\n<\/ul>\n<\/div>\n<\/div>\n<div style=\"clear: both; display: block; margin: 10px 0;\">\n<div style=\"clear: both; display: block; margin: 10px 0;\">\n<div  style=\"max-width:2317px;max-height:2560px\">\n<div style=\"clear: both; display: block; margin: 10px 0;\">\n<div style=\"clear: both; width: 100%; display: block; margin: 20px 0; padding: 0; float: none; position: static; text-align: center;\"><img decoding=\"async\"  src=\"https:\/\/a.allegroimg.com\/original\/116aea\/3044bdd14ea486f182af240deaf6\/GRILL-GAZOWY-Yao-5-1-19KW-zeliwny-ruszt-palnik-na-podczerwien-YATO-YG-20031-Kod-producenta-YG-20031\" srcset=\"https:\/\/a.allegroimg.com\/original\/116aea\/3044bdd14ea486f182af240deaf6\/GRILL-GAZOWY-Yao-5-1-19KW-zeliwny-ruszt-palnik-na-podczerwien-YATO-YG-20031-Kod-producenta-YG-20031 325w,https:\/\/a.allegroimg.com\/original\/116aea\/3044bdd14ea486f182af240deaf6\/GRILL-GAZOWY-Yao-5-1-19KW-zeliwny-ruszt-palnik-na-podczerwien-YATO-YG-20031-Kod-producenta-YG-20031 651w,https:\/\/a.allegroimg.com\/original\/116aea\/3044bdd14ea486f182af240deaf6\/GRILL-GAZOWY-Yao-5-1-19KW-zeliwny-ruszt-palnik-na-podczerwien-YATO-YG-20031-Kod-producenta-YG-20031 926w,https:\/\/a.allegroimg.com\/original\/116aea\/3044bdd14ea486f182af240deaf6\/GRILL-GAZOWY-Yao-5-1-19KW-zeliwny-ruszt-palnik-na-podczerwien-YATO-YG-20031-Kod-producenta-YG-20031 1303w,https:\/\/a.allegroimg.com\/original\/116aea\/3044bdd14ea486f182af240deaf6\/GRILL-GAZOWY-Yao-5-1-19KW-zeliwny-ruszt-palnik-na-podczerwien-YATO-YG-20031-Kod-producenta-YG-20031 2317w\" sizes=\"(min-width: 1200px) 560px, (min-width: 992px) 50vw, 100vw\" width=\"2317px\" alt=\"GRILL GAZOWY Yao 5+1 19KW \u017celiwny ruszt palnik na podczerwie\u0144 YATO YG-20031 Kod producenta YG-20031\" style=\"max-width: 100%; height: auto; display: block; margin: 0 auto;\"><\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div style=\"clear: both; display: block; margin: 10px 0;\">\n<div style=\"clear: both; display: block; margin: 10px 0;\">\n<div style=\"clear: both; display: block; margin: 10px 0;\">\n<div  style=\"max-width:2560px;max-height:2175px\">\n<div style=\"clear: both; display: block; margin: 10px 0;\">\n<div style=\"clear: both; width: 100%; display: block; margin: 20px 0; padding: 0; float: none; position: static; text-align: center;\"><img decoding=\"async\"  src=\"https:\/\/a.allegroimg.com\/original\/1160b7\/5b3cff434afcbe4ff2dd54927d9a\/GRILL-GAZOWY-Yao-5-1-19KW-zeliwny-ruszt-palnik-na-podczerwien-YATO-YG-20031-Marka-Yato\" srcset=\"https:\/\/a.allegroimg.com\/original\/1160b7\/5b3cff434afcbe4ff2dd54927d9a\/GRILL-GAZOWY-Yao-5-1-19KW-zeliwny-ruszt-palnik-na-podczerwien-YATO-YG-20031-Marka-Yato 360w,https:\/\/a.allegroimg.com\/original\/1160b7\/5b3cff434afcbe4ff2dd54927d9a\/GRILL-GAZOWY-Yao-5-1-19KW-zeliwny-ruszt-palnik-na-podczerwien-YATO-YG-20031-Marka-Yato 720w,https:\/\/a.allegroimg.com\/original\/1160b7\/5b3cff434afcbe4ff2dd54927d9a\/GRILL-GAZOWY-Yao-5-1-19KW-zeliwny-ruszt-palnik-na-podczerwien-YATO-YG-20031-Marka-Yato 1024w,https:\/\/a.allegroimg.com\/original\/1160b7\/5b3cff434afcbe4ff2dd54927d9a\/GRILL-GAZOWY-Yao-5-1-19KW-zeliwny-ruszt-palnik-na-podczerwien-YATO-YG-20031-Marka-Yato 1440w,https:\/\/a.allegroimg.com\/original\/1160b7\/5b3cff434afcbe4ff2dd54927d9a\/GRILL-GAZOWY-Yao-5-1-19KW-zeliwny-ruszt-palnik-na-podczerwien-YATO-YG-20031-Marka-Yato 2560w\" sizes=\"(min-width: 1200px) 560px, (min-width: 992px) 50vw, 100vw\" width=\"2560px\" alt=\"GRILL GAZOWY Yao 5+1 19KW \u017celiwny ruszt palnik na podczerwie\u0144 YATO YG-20031 Marka Yato\" style=\"max-width: 100%; height: auto; display: block; margin: 0 auto;\"><\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div style=\"clear: both; display: block; margin: 10px 0;\">\n<div style=\"clear: both; display: block; margin: 10px 0;\">\n<div  style=\"max-width:2560px;max-height:1959px\">\n<div style=\"clear: both; display: block; margin: 10px 0;\">\n<div style=\"clear: both; width: 100%; display: block; margin: 20px 0; padding: 0; float: none; position: static; text-align: center;\"><img decoding=\"async\"  src=\"https:\/\/a.allegroimg.com\/original\/11fafb\/9f07b6b84b2aa87a78a280feb619\/GRILL-GAZOWY-Yao-5-1-19KW-zeliwny-ruszt-palnik-na-podczerwien-YATO-YG-20031-Szerokosc-grilla-112-cm\" srcset=\"https:\/\/a.allegroimg.com\/original\/11fafb\/9f07b6b84b2aa87a78a280feb619\/GRILL-GAZOWY-Yao-5-1-19KW-zeliwny-ruszt-palnik-na-podczerwien-YATO-YG-20031-Szerokosc-grilla-112-cm 360w,https:\/\/a.allegroimg.com\/original\/11fafb\/9f07b6b84b2aa87a78a280feb619\/GRILL-GAZOWY-Yao-5-1-19KW-zeliwny-ruszt-palnik-na-podczerwien-YATO-YG-20031-Szerokosc-grilla-112-cm 720w,https:\/\/a.allegroimg.com\/original\/11fafb\/9f07b6b84b2aa87a78a280feb619\/GRILL-GAZOWY-Yao-5-1-19KW-zeliwny-ruszt-palnik-na-podczerwien-YATO-YG-20031-Szerokosc-grilla-112-cm 1024w,https:\/\/a.allegroimg.com\/original\/11fafb\/9f07b6b84b2aa87a78a280feb619\/GRILL-GAZOWY-Yao-5-1-19KW-zeliwny-ruszt-palnik-na-podczerwien-YATO-YG-20031-Szerokosc-grilla-112-cm 1440w,https:\/\/a.allegroimg.com\/original\/11fafb\/9f07b6b84b2aa87a78a280feb619\/GRILL-GAZOWY-Yao-5-1-19KW-zeliwny-ruszt-palnik-na-podczerwien-YATO-YG-20031-Szerokosc-grilla-112-cm 2560w\" sizes=\"(min-width: 1200px) 560px, (min-width: 992px) 50vw, 100vw\" width=\"2560px\" alt=\"GRILL GAZOWY Yao 5+1 19KW \u017celiwny ruszt palnik na podczerwie\u0144 YATO YG-20031 Szeroko\u015b\u0107 grilla 112 cm\" style=\"max-width: 100%; height: auto; display: block; margin: 0 auto;\"><\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div style=\"clear: both; display: block; margin: 10px 0;\">\n<div style=\"clear: both; display: block; margin: 10px 0;\">\n<div style=\"clear: both; display: block; margin: 10px 0;\">\n<div  style=\"max-width:1200px;max-height:421px\">\n<div style=\"clear: both; display: block; margin: 10px 0;\">\n<div style=\"clear: both; width: 100%; display: block; margin: 20px 0; padding: 0; float: none; position: static; text-align: center;\"><img decoding=\"async\"  src=\"https:\/\/a.allegroimg.com\/original\/113a91\/6ff038e84de89117ba6b34ef4741\/GRILL-GAZOWY-Yao-5-1-19KW-zeliwny-ruszt-palnik-na-podczerwien-YATO-YG-20031-Liczba-palnikow-5\" srcset=\"https:\/\/a.allegroimg.com\/original\/113a91\/6ff038e84de89117ba6b34ef4741\/GRILL-GAZOWY-Yao-5-1-19KW-zeliwny-ruszt-palnik-na-podczerwien-YATO-YG-20031-Liczba-palnikow-5 360w,https:\/\/a.allegroimg.com\/original\/113a91\/6ff038e84de89117ba6b34ef4741\/GRILL-GAZOWY-Yao-5-1-19KW-zeliwny-ruszt-palnik-na-podczerwien-YATO-YG-20031-Liczba-palnikow-5 720w,https:\/\/a.allegroimg.com\/original\/113a91\/6ff038e84de89117ba6b34ef4741\/GRILL-GAZOWY-Yao-5-1-19KW-zeliwny-ruszt-palnik-na-podczerwien-YATO-YG-20031-Liczba-palnikow-5 1024w,https:\/\/a.allegroimg.com\/original\/113a91\/6ff038e84de89117ba6b34ef4741\/GRILL-GAZOWY-Yao-5-1-19KW-zeliwny-ruszt-palnik-na-podczerwien-YATO-YG-20031-Liczba-palnikow-5 1200w,https:\/\/a.allegroimg.com\/original\/113a91\/6ff038e84de89117ba6b34ef4741\/GRILL-GAZOWY-Yao-5-1-19KW-zeliwny-ruszt-palnik-na-podczerwien-YATO-YG-20031-Liczba-palnikow-5 1200w\" sizes=\"100vw\" width=\"1200px\" alt=\"GRILL GAZOWY Yao 5+1 19KW \u017celiwny ruszt palnik na podczerwie\u0144 YATO YG-20031 Liczba palnik\u00f3w 5\" style=\"max-width: 100%; height: auto; display: block; margin: 0 auto;\"><\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div style=\"clear: both; display: block; margin: 10px 0;\">\n","protected":false},"excerpt":{"rendered":"<p>YATO GRILL GAZOWY YAO 5+1 19KW CZARNY YG-20031<\/p>\n<p>Grill gazowy yao 5+1 19kw czarny<\/p>\n<p>Wolnostoj\u0105cy grill gazowy serii Yao&nbsp;z 6 palnikami&nbsp;o \u0142\u0105cznej mocy 19,5&nbsp;kW i praktycznymi dodatkami u\u0142atwiaj\u0105cymi przygotowywanie potraw na \u015bwie\u017cym powietrzu. Wyposa\u017cony w 3&nbsp;\u017celiwne&nbsp;ruszty o du\u017cej powierzchni roboczej i&nbsp;kratk\u0119 podgrzewaj\u0105c\u0105 z wysokiej jako\u015bci&nbsp;stali nierdzewnej, trwa\u0142e i odporne na korozj\u0119 oraz uszkodzenia.&nbsp; &nbsp;<\/p>\n<p>Parametry:<\/p>\n<p>wymiary grilla:&nbsp;1330 x 570 x 1120 mm<\/p>\n<p>materia\u0142: stal malowana proszkowo na kolor czarny<\/p>\n<p>materia\u0142 ruszt\u00f3w: \u017celiwo<\/p>\n","protected":false},"featured_media":15362,"template":"","meta":{"_uag_custom_page_level_css":""},"product_brand":[817],"product_cat":[832,795,541],"product_tag":[],"class_list":{"0":"post-15359","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_brand-yato","7":"product_cat-grille-gazowe","8":"product_cat-grillowanie","9":"product_cat-ogrod","11":"first","12":"instock","13":"sale","14":"shipping-taxable","15":"purchasable","16":"product-type-simple"},"uagb_featured_image_src":{"full":["https:\/\/torxino.shop\/grill\/wp-content\/uploads\/2026\/03\/allegro-image-15359.jpg",2560,2278,false],"thumbnail":["https:\/\/torxino.shop\/grill\/wp-content\/uploads\/2026\/03\/allegro-image-15359-150x150.jpg",150,150,true],"medium":["https:\/\/torxino.shop\/grill\/wp-content\/uploads\/2026\/03\/allegro-image-15359-300x267.jpg",300,267,true],"medium_large":["https:\/\/torxino.shop\/grill\/wp-content\/uploads\/2026\/03\/allegro-image-15359-768x683.jpg",768,683,true],"large":["https:\/\/torxino.shop\/grill\/wp-content\/uploads\/2026\/03\/allegro-image-15359-1024x911.jpg",1024,911,true],"1536x1536":["https:\/\/torxino.shop\/grill\/wp-content\/uploads\/2026\/03\/allegro-image-15359-1536x1367.jpg",1536,1367,true],"2048x2048":["https:\/\/torxino.shop\/grill\/wp-content\/uploads\/2026\/03\/allegro-image-15359-2048x1822.jpg",2048,1822,true],"woocommerce_thumbnail":["https:\/\/torxino.shop\/grill\/wp-content\/uploads\/2026\/03\/allegro-image-15359-300x300.jpg",300,300,true],"woocommerce_single":["https:\/\/torxino.shop\/grill\/wp-content\/uploads\/2026\/03\/allegro-image-15359-600x534.jpg",600,534,true],"woocommerce_gallery_thumbnail":["https:\/\/torxino.shop\/grill\/wp-content\/uploads\/2026\/03\/allegro-image-15359-100x100.jpg",100,100,true]},"uagb_author_info":{"display_name":"admin","author_link":"https:\/\/torxino.shop\/grill\/author\/"},"uagb_comment_info":0,"uagb_excerpt":"YATO GRILL GAZOWY YAO 5+1 19KW CZARNY YG-20031 Grill gazowy yao 5+1 19kw czarny Wolnostoj\u0105cy grill gazowy serii Yao&nbsp;z 6 palnikami&nbsp;o \u0142\u0105cznej mocy 19,5&nbsp;kW i praktycznymi dodatkami u\u0142atwiaj\u0105cymi przygotowywanie potraw na \u015bwie\u017cym powietrzu. Wyposa\u017cony w 3&nbsp;\u017celiwne&nbsp;ruszty o du\u017cej powierzchni roboczej i&nbsp;kratk\u0119 podgrzewaj\u0105c\u0105 z wysokiej jako\u015bci&nbsp;stali nierdzewnej, trwa\u0142e i odporne na korozj\u0119 oraz uszkodzenia.&nbsp; &nbsp; Parametry:&hellip;","_links":{"self":[{"href":"https:\/\/torxino.shop\/grill\/wp-json\/wp\/v2\/product\/15359","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/torxino.shop\/grill\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/torxino.shop\/grill\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/torxino.shop\/grill\/wp-json\/wp\/v2\/media\/15362"}],"wp:attachment":[{"href":"https:\/\/torxino.shop\/grill\/wp-json\/wp\/v2\/media?parent=15359"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/torxino.shop\/grill\/wp-json\/wp\/v2\/product_brand?post=15359"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/torxino.shop\/grill\/wp-json\/wp\/v2\/product_cat?post=15359"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/torxino.shop\/grill\/wp-json\/wp\/v2\/product_tag?post=15359"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}